{"id":1323,"date":"2023-05-25T17:43:53","date_gmt":"2023-05-25T15:43:53","guid":{"rendered":"https:\/\/valvi-big.com\/geschaftsbedingungen\/"},"modified":"2024-01-04T22:29:25","modified_gmt":"2024-01-04T21:29:25","slug":"datenschutzerklarung","status":"publish","type":"page","link":"https:\/\/valvi-big.com\/de\/datenschutzerklarung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1323\" class=\"elementor elementor-1323\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-987dc79 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"987dc79\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a41a7ec\" data-id=\"3a41a7ec\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-615e65f1 elementor-widget elementor-widget-shortcode\" data-id=\"615e65f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<!-- This legal document was generated by Complianz Terms &amp; Conditions https:\/\/wordpress.org\/plugins\/complianz-terms-conditions -->\n<div id=\"cmplz-document\" class=\"cmplz-document cmplz-terms-conditions\"><p><i>Die Allgemeinen Gesch\u00e4ftsbedingungen wurden zuletzt am 19. Juli 2024 aktualisiert<\/i><\/p><h2>1. Einf\u00fchrung<\/h2><p>Diese Allgemeinen Gesch\u00e4ftsbedingungen gelten f\u00fcr diese Website und f\u00fcr die Transaktionen im Zusammenhang mit unseren Produkten und Dienstleistungen.&nbsp;Du bist m\u00f6glicherweise an zus\u00e4tzliche Vertr\u00e4ge gebunden, die sich auf deine Beziehung zu uns oder auf Produkte oder Dienstleistungen beziehen, die du von uns erh\u00e4ltst.&nbsp;Wenn Bestimmungen der Zusatzvertr\u00e4ge mit Bestimmungen dieser Bedingungen in Konflikt stehen, haben die Bestimmungen dieser Zusatzvertr\u00e4ge Vorrang.<\/p><h2>2. Verbindlichkeit<\/h2><p>Durch die Registrierung, den Zugriff auf oder die anderweitige Nutzung dieser Website erkl\u00e4rst du dich hiermit einverstanden, an diese unten aufgef\u00fchrten Allgemeinen Gesch\u00e4ftsbedingungen gebunden zu sein.&nbsp;Die blo\u00dfe Nutzung dieser Website setzt die Kenntnis und Akzeptanz dieser Allgemeinen Gesch\u00e4ftsbedingungen voraus.&nbsp;In bestimmten F\u00e4llen k\u00f6nnen wir dich auch bitten, ausdr\u00fccklich zuzustimmen.<\/p><h2>3. Elektronische Kommunikation<\/h2><p>Durch die Nutzung dieser Website oder die Kommunikation mit uns auf elektronischem Wege erkl\u00e4rst du dich damit einverstanden und erkennst an, dass wir auf unserer Website elektronisch mit dir kommunizieren oder dir eine E-Mail senden k\u00f6nnen, und stimmst zu, dass alle Vereinbarungen, Mitteilungen, Offenlegungen und sonstigen Mitteilungen, die wir dir elektronisch zusenden, alle gesetzlichen Anforderungen erf\u00fcllen. Beinhaltet zudem, aber nicht auf die Anforderung beschr\u00e4nkt, dass solche Mitteilungen schriftlich erfolgen sollten.<\/p><h2>4. Geistiges Eigentum<\/h2><p>Wir oder unsere Lizenzgeber besitzen und kontrollieren alle Urheberrechte und sonstigen Rechte an geistigem Eigentum auf der Website sowie die Daten, Informationen und sonstigen Ressourcen, die auf der Website angezeigt werden oder auf der Website zug\u00e4nglich ist.<\/p><p class=\"cmplz-subtitle\">4.1 Alle Rechte vorbehalten<\/p><p>Sofern bestimmte Inhalte nichts anderes vorschreiben, wird dir keine Lizenz oder ein anderes Recht unter Urheber-, Marken-, Patent- oder anderen Rechten an geistigem Eigentum gew\u00e4hrt. &nbsp;Dies bedeutet, dass du keine Ressourcen auf dieser Website verwendest, kopierst, reproduzierst, ausf\u00fchrst, anzeigst, verteilst, in ein elektronisches Medium einbettest, \u00e4nderst, zur\u00fcckentwickelst, dekompilierst, \u00fcbergibst, herunterl\u00e4dst, \u00fcbertragst, monetarisierst, verkaufst, vermarktest oder kommerzialisierst in jeglicher Form, ohne unsere vorherige schriftliche Genehmigung, au\u00dfer und nur insoweit, als dies in den Bestimmungen des zwingenden Rechts (wie dem Recht auf Zitat) anders festgelegt ist.<\/p><h2>5. Newsletter<\/h2><p>Ungeachtet des Obigen, kannst du unseren Newsletter in elektronischer Form an andere Personen weiterleiten, die m\u00f6glicherweise an einem Besuch unserer Website interessiert sind.<\/p><h2>6. Eigentum Drittanbieter<\/h2><p>Unsere Website kann Hyperlinks oder andere Verweise auf Websites anderer Parteien enthalten.&nbsp;Wir \u00fcberwachen oder \u00fcberpr\u00fcfen nicht den Inhalt der Websites anderer Parteien, auf die von dieser Website aus verwiesen wird.&nbsp;Produkte oder Dienstleistungen, die von anderen Websites angeboten werden, unterliegen den Allgemeinen Gesch\u00e4ftsbedingungen dieser Dritten.&nbsp;Auf diesen Websites ge\u00e4u\u00dferte Meinungen oder Materialien werden von uns nicht unbedingt geteilt oder unterst\u00fctzt.<\/p><p>Wir sind nicht verantwortlich f\u00fcr Datenschutzpraktiken oder Inhalte dieser Websites.&nbsp;Du tr\u00e4gst alle Risiken, die mit der Nutzung dieser Websites und damit verbundener Dienste Dritter verbunden sind.&nbsp;Wir \u00fcbernehmen keine Verantwortung f\u00fcr Verluste oder Sch\u00e4den jeglicher Art, die sich aus deiner Weitergabe personenbezogener Daten an Dritte ergeben.<\/p><h2>7. Verantwortungsbewusster Umgang<\/h2><p>Durch den Besuch unserer Website erkl\u00e4rst du dich damit einverstanden, diese nur f\u00fcr die Zwecke zu verwenden, die durch diese Bedingungen, zus\u00e4tzliche Vertr\u00e4ge mit uns sowie geltende Gesetze, Vorschriften und allgemein anerkannte Online-Praktiken und Branchenrichtlinien beabsichtigt und gestattet sind.&nbsp;Du darfst unsere Website oder Dienste nicht verwenden, um Material zu verwenden, zu ver\u00f6ffentlichen oder zu verbreiten, das aus b\u00f6sartiger Computersoftware besteht (oder mit dieser verlinkt ist). Verwende die auf unserer Website gesammelten Daten f\u00fcr Direktmarketingaktivit\u00e4ten oder f\u00fchre systematische oder automatisierte Datenerfassungsaktivit\u00e4ten auf oder in Bezug auf unsere Website durch.<\/p><p>Die Teilnahme an Aktivit\u00e4ten, die Sch\u00e4den an der Website verursachen oder verursachen k\u00f6nnen oder die Leistung, Verf\u00fcgbarkeit oder Zug\u00e4nglichkeit der Website beeintr\u00e4chtigen, ist strengstens untersagt.<\/p><h2>8. R\u00fcckerstattungs- und R\u00fcckgaberecht<\/h2><p class=\"cmplz-subtitle\">8.1 Recht des Widerrufs<\/p><p>Du hast das Recht, innerhalb von 14 Tagen ohne Angabe von Gr\u00fcnden von diesem Vertrag zur\u00fcckzutreten.<\/p><p>Die Widerrufsfrist l\u00e4uft nach 14 Tagen ab dem Tag des Vertragsschlusses ab.<\/p><p>To exercise your right of withdrawal, you must inform us of your decision to withdraw from this contract by an unequivocal statement.&nbsp;To this end, you may use the <a href=\"\">withdrawal function available<\/a>.&nbsp;You are, however, free to express your intention to withdraw from the contract by making an unequivocal statement in any other suitable way.<\/p><p>You can also submit any other unequivocal statement on our <a href=\"https:\/\/valvi-big.com\/contact\/\"> website<\/a>.<\/p><p>Wenn du diese Option nutzt, werden wir dir unverz\u00fcglich eine Empfangsbest\u00e4tigung \u00fcber einen solchen Widerruf auf einem dauerhaften Medium (z. B. per E-Mail) \u00fcbermitteln.<\/p><p>Um die Widerrufsfrist einzuhalten, reicht es aus, dass du deine Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absendest.<\/p><p class=\"cmplz-subtitle\">8.2 Auswirkungen des Widerrufs<\/p><p>Wenn du von diesem Vertrag zur\u00fccktrittst, erstatten wir dir alle von dir erhaltenen Zahlungen, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich aus deiner Wahl einer anderen Lieferart als der von dir angebotenen kosteng\u00fcnstigsten Standardlieferungsart ergibt), unverz\u00fcglich und in jedem Fall sp\u00e4testens 14 Tage ab dem Tag, an dem wir \u00fcber deine Entscheidung zum R\u00fccktritt von diesem Vertrag informiert werden.&nbsp;Wir werden diese Erstattung mit denselben Zahlungsmitteln durchf\u00fchren, die du f\u00fcr die urspr\u00fcngliche Transaktion verwendet hast, sofern du nicht ausdr\u00fccklich etwas anderes vereinbart hattest. In jedem Fall fallen f\u00fcr diese Erstattung keine Geb\u00fchren an. <\/p><p>Wenn du w\u00e4hrend der Widerrufsfrist mit der Leistungserbringung begonnen hast, zahlst du uns einen Betrag, der im Verh\u00e4ltnis zu den geleisteten Leistungen steht, bis du uns deinen R\u00fccktritt von diesem Vertrag im Vergleich zur vollst\u00e4ndigen Deckung des Vertrages mitgeteilt hast.<\/p><p>Bitte beachte, dass es einige gesetzliche Ausnahmen vom Widerrufsrecht gibt und einige Artikel daher nicht zur\u00fcckgegeben oder umgetauscht werden k\u00f6nnen.&nbsp;Wir werden dich informieren, wenn dies in deinem speziellen Fall zutrifft.<\/p><h2>9. Ideeneinreichung<\/h2><p>Reiche keine Ideen, Erfindungen, Werke der Urheberschaft oder andere Informationen ein, die als dein eigenes geistiges Eigentum angesehen werden k\u00f6nnen und welche du uns pr\u00e4sentieren m\u00f6chtest, es sei denn, wir haben zuvor eine Vereinbarung \u00fcber das geistige Eigentum oder eine Geheimhaltungsvereinbarung unterzeichnet.&nbsp;Wenn du uns dies ohne eine solche schriftliche Vereinbarung mitteilst, gew\u00e4hrst du uns eine weltweite, unwiderrufliche, nicht exklusive, lizenzgeb\u00fchrenfreie Lizenz zur Nutzung, Reproduktion, Speicherung, Anpassung, Ver\u00f6ffentlichung, \u00dcbersetzung und Verbreitung deiner Inhalte in bestehenden oder zuk\u00fcnftigen Medien .<\/p><h2>10. Beendigung der Nutzung<\/h2><p>Wir k\u00f6nnen nach eigenem Ermessen den Zugriff auf die Website oder einen darauf befindlichen Service jederzeit vor\u00fcbergehend oder dauerhaft \u00e4ndern oder einstellen.&nbsp;Du erkl\u00e4rst dich damit einverstanden, dass wir weder dir noch Dritten gegen\u00fcber f\u00fcr solche \u00c4nderungen, Aussetzungen oder Unterbrechungen deines Zugriffs auf oder deiner Nutzung der Website oder von Inhalten, die dich m\u00f6glicherweise auf der Website geteilt haben, haften.&nbsp;Du hast keinen Anspruch auf Entsch\u00e4digung oder sonstige Zahlung, selbst wenn bestimmte Funktionen, Einstellungen und\/oder Inhalte, die du beigesteuert hast oder auf die du dich verl\u00e4sst, dauerhaft verloren gehen.&nbsp;Du darfst keine Zugriffsbeschr\u00e4nkungsma\u00dfnahmen auf unserer Website umgehen oder versuchen, sie zu umgehen.<\/p><h2>11. Garantien und Haftung<\/h2><p>Durch nichts in diesem Abschnitt wird eine gesetzlich implizierte Garantie eingeschr\u00e4nkt oder ausgeschlossen, deren Einschr\u00e4nkung oder Ausschluss rechtswidrig w\u00e4re.&nbsp;Diese Website und alle Inhalte der Website werden \"wie sie sind\" und \"wie verf\u00fcgbar\" bereitgestellt und k\u00f6nnen Ungenauigkeiten oder Tippfehler enthalten.&nbsp;Wir lehnen ausdr\u00fccklich jegliche ausdr\u00fcckliche oder stillschweigende Gew\u00e4hrleistung jeglicher Art hinsichtlich der Verf\u00fcgbarkeit, Richtigkeit oder Vollst\u00e4ndigkeit des Inhalts ab.&nbsp;Wir \u00fcbernehmen keine Garantie daf\u00fcr, dass:<\/p><p><ul>\n                    <li>Diese Website oder unser Inhalt wird deinen Anforderungen entsprechen.<\/li>\n                    <li>Diese Website wird ununterbrochen, zeitnah, sicher oder fehlerfrei verf\u00fcgbar sein.<\/li>\n        <\/ul><\/p><p>Die folgenden Bestimmungen dieses Abschnitts gelten im gesetzlich zul\u00e4ssigen H\u00f6chstma\u00df und schr\u00e4nken unsere Haftung in Bezug auf Angelegenheiten, die f\u00fcr uns rechtswidrig oder rechtswidrig w\u00e4ren, unsere Haftung einzuschr\u00e4nken oder auszuschlie\u00dfen, nicht ein oder aus.&nbsp;In keinem Fall haften wir f\u00fcr direkte oder indirekte Sch\u00e4den (einschlie\u00dflich Sch\u00e4den f\u00fcr entgangenen Gewinn oder Umsatz, Verlust oder Besch\u00e4digung von Daten, Software oder Datenbank oder Verlust oder Besch\u00e4digung von Eigentum oder Daten), die dir oder Drittparteien entstehen, die sich aus deinem Zugriff auf oder deiner Nutzung unserer Website ergibt.<\/p><p>Sofern in einem zus\u00e4tzlichen Vertrag nicht ausdr\u00fccklich etwas anderes bestimmt ist, haften wir dir gegen\u00fcber maximal f\u00fcr alle Sch\u00e4den, die aus der Website oder mit Produkten und Dienstleistungen entstehen oder damit in Verbindung stehen, die \u00fcber die Website vermarktet oder verkauft werden, unabh\u00e4ngig von der Form der rechtlichen Schritte, die eine Haftung auferlegen ( Ob vertraglich, nach Billigkeit, Fahrl\u00e4ssigkeit, vors\u00e4tzlichem Verhalten, unerlaubter Handlung oder auf andere Weise) wird auf den Gesamtpreis begrenzt, den du an uns gezahlt hast, um solche Produkte oder Dienstleistungen zu kaufen oder die Website zu nutzen.&nbsp;Diese Begrenzung gilt insgesamt f\u00fcr alle deine Anspr\u00fcche, Handlungen und Klagegr\u00fcnde jeglicher Art und Art.<\/p><h2>12. Privatsph\u00e4re<\/h2><p>Um auf unsere Website und\/oder Dienstleistungen zugreifen zu k\u00f6nnen, musst du im Rahmen des Registrierungsprozesses m\u00f6glicherweise bestimmte Informationen \u00fcber dich selbst angeben.&nbsp;Du stimmst zu, dass alle von dir angegebenen Informationen immer genau, korrekt und aktuell sind.<\/p><p>Wir haben eine Richtlinie entwickelt, um eventuelle Datenschutzbedenken auszur\u00e4umen.&nbsp;For more information, please see our <a href=\"https:\/\/valvi-big.com\/de\/datenschutzerklarung\/\">Privacy Statement<\/a> and our <a href=\"https:\/\/valvi-big.com\/cookie-richtlinie-eu\/?cmplz_region_redirect=true\">Cookie Policy<\/a>.<\/p><h2>13. Barrierefreiheit<\/h2><p>Wir verpflichten uns, die von uns bereitgestellten Inhalte f\u00fcr Menschen mit Behinderungen zug\u00e4nglich zu machen.&nbsp;Wenn du eine Behinderung\/Beeintr\u00e4chtigung hast und aufgrund dieser nicht auf einen Teil unserer Website zugreifen kannst, bitten wir dich, uns eine Mitteilung mit einer detaillierten Beschreibung des aufgetretenen Problems zu senden.&nbsp;Wenn das Problem gem\u00e4\u00df den branchen\u00fcblichen Informationstechnologie-Tools und -Techniken leicht zu identifizieren und zu l\u00f6sen ist, werden wir es umgehend beheben.<\/p><h2>14. Exportbeschr\u00e4nkungen \/ Einhaltung von Gesetzen<\/h2><p>Der Zugriff auf die Website aus Gebieten oder L\u00e4ndern, in denen der Inhalt oder Kauf der auf der Website verkauften Produkte oder Dienstleistungen illegal ist, ist verboten.&nbsp;Du darfst diese Website nicht unter Versto\u00df gegen die Exportgesetze und -bestimmungen von Deutschland verwenden.<\/p><h2>15. Partnerschafts-Marketing<\/h2><p>\u00dcber diese Website k\u00f6nnen wir Partnerschafts-Marketing betreiben, wobei wir einen Prozentsatz oder eine Provision f\u00fcr den Verkauf von Dienstleistungen oder Produkten auf oder \u00fcber diese Website erhalten.&nbsp;Wir k\u00f6nnen auch Sponsoring oder andere Formen der Werbeverg\u00fctung von Unternehmen akzeptieren.&nbsp;Diese Offenlegung soll den gesetzlichen Anforderungen in Bezug auf Marketing und Werbung entsprechen, die m\u00f6glicherweise gelten, wie z. B. den Regeln der US-amerikanischen Federal Trade Commission.<\/p><h2>16. Zuordnung<\/h2><p>Ohne unsere vorherige schriftliche Zustimmung darfst du deine Rechte und\/oder Pflichten aus diesen Gesch\u00e4ftsbedingungen weder ganz noch teilweise an Dritte abtreten, \u00fcbertragen oder an Dritte weitergeben.&nbsp;Jede angebliche Abtretung, die gegen diesen Abschnitt verst\u00f6\u00dft, ist nichtig.<\/p><h2>17. Verst\u00f6\u00dfe gegen diese Allgemeinen Gesch\u00e4ftsbedingungen<\/h2><p>Ungeachtet unserer anderen Rechte aus diesen Allgemeinen Gesch\u00e4ftsbedingungen k\u00f6nnen wir, wenn du in irgendeiner Weise gegen diese Allgemeinen Gesch\u00e4ftsbedingungen verst\u00f6\u00dft, Ma\u00dfnahmen ergreifen, die wir f\u00fcr angemessen halten, um den Versto\u00df zu behandeln, einschlie\u00dflich der vor\u00fcbergehenden oder dauerhaften Sperrung deines Zugriffs auf die Website und mit der Kontaktaufnahme deines Internetdienstanbieter mit der Aufforderung deinen Zugang zur Website zu sperren und\/oder rechtliche Schritte gegen dich einzuleiten.<\/p><h2>18. H\u00f6here Gewalt<\/h2><p>Mit Ausnahme der Zahlungsverpflichtung, eine Verz\u00f6gerung, ein Vers\u00e4umnis oder eine Unterlassung einer Partei bei der Erf\u00fcllung oder Einhaltung einer ihrer Verpflichtungen aus diesem Vertrag, gilt nicht als Versto\u00df gegen diese Allgemeinen Gesch\u00e4ftsbedingungen, wenn und solange eine solche Verz\u00f6gerung, ein Vers\u00e4umnis oder eine Unterlassung aus einem \u00fcber den vern\u00fcnftigen Grund hinausgehenden Grund der angemessenen Kontrolle dieser Partei liegt.<\/p><h2>19. Entsch\u00e4digung<\/h2><p>Du erkl\u00e4rst dich damit einverstanden, uns von s\u00e4mtlichen Anspr\u00fcchen, Verbindlichkeiten, Sch\u00e4den, Verlusten und Kosten im Zusammenhang mit deiner Verletzung dieser Allgemeinen Gesch\u00e4ftsbedingungen und der geltenden Gesetze, einschlie\u00dflich geistiger Eigentumsrechte und Datenschutzrechte, freizustellen, zu verteidigen und schadlos zu halten.&nbsp;Du wirst uns unverz\u00fcglich unsere Sch\u00e4den, Verluste, Kosten und Aufwendungen im Zusammenhang mit oder aus solchen Anspr\u00fcchen erstatten.<\/p><h2>20. Verzicht<\/h2><p>Das Vers\u00e4umnis, eine der Bestimmungen dieser Allgemeinen Gesch\u00e4ftsbedingungen und einer Vereinbarung durchzusetzen, oder das Vers\u00e4umnis, eine K\u00fcndigungsoption auszu\u00fcben, gilt nicht als Verzicht auf diese Bestimmungen und ber\u00fchrt nicht die G\u00fcltigkeit dieser Allgemeinen Gesch\u00e4ftsbedingungen oder einer dieser Vereinbarungen oder ein Teil davon oder das Recht danach, jede einzelne Bestimmung durchzusetzen.<\/p><h2>21. Sprache<\/h2><p>Diese Allgemeinen Gesch\u00e4ftsbedingungen werden ausschlie\u00dflich in Deutsch interpretiert und ausgelegt.&nbsp;Alle Mitteilungen und Korrespondenzen werden ausschlie\u00dflich in dieser Sprache verfasst.<\/p><h2>22. Komplette Vereinbarung<\/h2><p>These Terms and Conditions, together with our <a href=\"https:\/\/valvi-big.com\/de\/datenschutzerklarung\/\">privacy statement<\/a> and <a href=\"https:\/\/valvi-big.com\/cookie-richtlinie-eu\/?cmplz_region_redirect=true\">cookie policy<\/a>, constitute the entire agreement between you and Valvi Big GmbH in relation to your use of this website.<\/p><h2>23. Aktualisierung dieser Allgemeinen Gesch\u00e4ftsbedingungen<\/h2><p>Wir k\u00f6nnen diese Allgemeinen Gesch\u00e4ftsbedingungen von Zeit zu Zeit aktualisieren.&nbsp;Das zu Beginn dieser Allgemeinen Gesch\u00e4ftsbedingungen angegebene Datum ist das letzte \u00dcberarbeitungsdatum.&nbsp;Wir werden dich schriftlich \u00fcber \u00c4nderungen oder Aktualisierungen informieren, und die \u00fcberarbeiteten Allgemeinen Gesch\u00e4ftsbedingungen werden ab dem Datum wirksam, an dem wir dich dar\u00fcber informieren.&nbsp;Deine fortgesetzte Nutzung dieser Website nach der Ver\u00f6ffentlichung von \u00c4nderungen oder Aktualisierungen gilt als Hinweis auf deine Zustimmung zur Einhaltung und Bindung dieser Allgemeinen Gesch\u00e4ftsbedingungen.&nbsp;Um eine fr\u00fchere Version dieser Allgemeinen Gesch\u00e4ftsbedingungen anzufordern, kontaktiere uns bitte.<\/p><h2>24. Rechtswahl und Gerichtsstand<\/h2><p>Diese Allgemeinen Gesch\u00e4ftsbedingungen unterliegen den Gesetzen von Deutschland. &nbsp;F\u00fcr alle Streitigkeiten im Zusammenhang mit diesen Allgemeinen Gesch\u00e4ftsbedingungen sind die Gerichte von Deutschland zust\u00e4ndig.&nbsp;Wenn ein Teil oder eine Bestimmung dieser Allgemeinen Gesch\u00e4ftsbedingungen von einem Gericht oder einer anderen Beh\u00f6rde als ung\u00fcltig und \/ oder nach geltendem Recht nicht durchsetzbar befunden wird, wird dieser Teil oder diese Bestimmung im maximal zul\u00e4ssigen Umfang ge\u00e4ndert, gel\u00f6scht und \/ oder durchgesetzt die Absicht dieser Allgemeinen Gesch\u00e4ftsbedingungen verwirklicht.&nbsp;Die \u00fcbrigen Bestimmungen bleiben unber\u00fchrt.<\/p><h2>25. Kontaktinformationen<\/h2><p>Diese Website geh\u00f6rt und wird betrieben von Valvi Big GmbH .<\/p><p>You may contact us regarding these Terms and Conditions through our <a href=\"https:\/\/valvi-big.com\/contact\/\">contact<\/a> page.<\/p><h2>26. Herunterladen<\/h2><p>You can also <a href=\"https:\/\/valvi-big.com\/wp-content\/plugins\/complianz-terms-conditions\/download.php\">download<\/a> our Terms and Conditions as a PDF.<\/p><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1323","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ValVi Big<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valvi-big.com\/de\/datenschutzerklarung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ValVi Big\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valvi-big.com\/de\/datenschutzerklarung\/\" \/>\n<meta property=\"og:site_name\" content=\"ValVi Big\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-04T21:29:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valvi-big.com\/wp-content\/uploads\/2023\/05\/cropped-IMG_2318-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valvi-big.com\\\/datenschutzerklarung\\\/\",\"url\":\"https:\\\/\\\/valvi-big.com\\\/datenschutzerklarung\\\/\",\"name\":\"ValVi Big\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valvi-big.com\\\/#website\"},\"datePublished\":\"2023-05-25T15:43:53+00:00\",\"dateModified\":\"2024-01-04T21:29:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valvi-big.com\\\/datenschutzerklarung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valvi-big.com\\\/datenschutzerklarung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valvi-big.com\\\/datenschutzerklarung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/valvi-big.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valvi-big.com\\\/#website\",\"url\":\"https:\\\/\\\/valvi-big.com\\\/\",\"name\":\"ValVi-Big\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/valvi-big.com\\\/#organization\"},\"alternateName\":\"ValVi-Big\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valvi-big.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/valvi-big.com\\\/#organization\",\"name\":\"ValVi Big\",\"alternateName\":\"ValVi Big\",\"url\":\"https:\\\/\\\/valvi-big.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/valvi-big.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/valvi-big.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-IMG_2318-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/valvi-big.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-IMG_2318-1.jpeg\",\"width\":512,\"height\":512,\"caption\":\"ValVi Big\"},\"image\":{\"@id\":\"https:\\\/\\\/valvi-big.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ValVi Big","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valvi-big.com\/de\/datenschutzerklarung\/","og_locale":"de_DE","og_type":"article","og_title":"ValVi Big","og_url":"https:\/\/valvi-big.com\/de\/datenschutzerklarung\/","og_site_name":"ValVi Big","article_modified_time":"2024-01-04T21:29:25+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/valvi-big.com\/wp-content\/uploads\/2023\/05\/cropped-IMG_2318-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/valvi-big.com\/datenschutzerklarung\/","url":"https:\/\/valvi-big.com\/datenschutzerklarung\/","name":"ValVi Big","isPartOf":{"@id":"https:\/\/valvi-big.com\/#website"},"datePublished":"2023-05-25T15:43:53+00:00","dateModified":"2024-01-04T21:29:25+00:00","breadcrumb":{"@id":"https:\/\/valvi-big.com\/datenschutzerklarung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valvi-big.com\/datenschutzerklarung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/valvi-big.com\/datenschutzerklarung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/valvi-big.com\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/valvi-big.com\/#website","url":"https:\/\/valvi-big.com\/","name":"ValVi-Big","description":"","publisher":{"@id":"https:\/\/valvi-big.com\/#organization"},"alternateName":"ValVi-Big","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valvi-big.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/valvi-big.com\/#organization","name":"ValVi Big","alternateName":"ValVi Big","url":"https:\/\/valvi-big.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/valvi-big.com\/#\/schema\/logo\/image\/","url":"https:\/\/valvi-big.com\/wp-content\/uploads\/2023\/05\/cropped-IMG_2318-1.jpeg","contentUrl":"https:\/\/valvi-big.com\/wp-content\/uploads\/2023\/05\/cropped-IMG_2318-1.jpeg","width":512,"height":512,"caption":"ValVi Big"},"image":{"@id":"https:\/\/valvi-big.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/valvi-big.com\/de\/wp-json\/wp\/v2\/pages\/1323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valvi-big.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/valvi-big.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/valvi-big.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/valvi-big.com\/de\/wp-json\/wp\/v2\/comments?post=1323"}],"version-history":[{"count":10,"href":"https:\/\/valvi-big.com\/de\/wp-json\/wp\/v2\/pages\/1323\/revisions"}],"predecessor-version":[{"id":4786,"href":"https:\/\/valvi-big.com\/de\/wp-json\/wp\/v2\/pages\/1323\/revisions\/4786"}],"wp:attachment":[{"href":"https:\/\/valvi-big.com\/de\/wp-json\/wp\/v2\/media?parent=1323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}